{"id":87814,"date":"2026-02-05T21:11:09","date_gmt":"2026-02-06T00:11:09","guid":{"rendered":"https:\/\/www.tvnovelas.com.br\/tvnews\/?p=87814"},"modified":"2026-02-05T21:11:09","modified_gmt":"2026-02-06T00:11:09","slug":"em-mae-nos-capitulos-da-semana-9-a-13-2","status":"publish","type":"post","link":"https:\/\/www.tvnovelas.com.br\/tvnews\/em-mae-nos-capitulos-da-semana-9-a-13-2\/","title":{"rendered":"Em M\u00e3e nos cap\u00edtulos da semana 9 a 13\/2"},"content":{"rendered":"<div style=\"background-color: #f5e7c6; border-style: solid; border-width: 0px 0px 10px 0px; solid green; border-radius: 30px; padding: 10px; font-size: 125%; text-align: justify;\">\n.<br \/>\n<figure id=\"attachment_87815\" aria-describedby=\"caption-attachment-87815\" style=\"width: 728px\" class=\"wp-caption alignnone\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"wp-image-87815 size-full\" title=\"(Foto: Record TV\/M\u00e3e)\" src=\"https:\/\/i0.wp.com\/www.tvnovelas.com.br\/tvnews\/wp-content\/uploads\/2026\/02\/12729-1.jpg?resize=728%2C410&#038;ssl=1\" alt=\"Foto em Em M\u00e3e nos cap\u00edtulos da semana 9 a 13\/2 \" width=\"728\" height=\"410\" srcset=\"https:\/\/i0.wp.com\/www.tvnovelas.com.br\/tvnews\/wp-content\/uploads\/2026\/02\/12729-1.jpg?w=728&amp;ssl=1 728w, https:\/\/i0.wp.com\/www.tvnovelas.com.br\/tvnews\/wp-content\/uploads\/2026\/02\/12729-1.jpg?resize=250%2C141&amp;ssl=1 250w\" sizes=\"(max-width: 728px) 100vw, 728px\" \/><figcaption id=\"caption-attachment-87815\" class=\"wp-caption-text\">Em M\u00e3e nos cap\u00edtulos da semana 9 a 13\/2<\/figcaption><\/figure><br \/>\n<strong style=\"color: #213c51; font-size: 120%;\">Nos pr\u00f3ximos cap\u00edtulos de M\u00e3e, <\/strong><span style=\"color: #213c51; font-size: 120%;\">Melek insiste para que Sule denuncie Cengiz, mas ela teme perder o marido; Sule chega de t\u00e1xi ao galp\u00e3o atr\u00e1s de Cengiz; Sule implora para Cengiz n\u00e3o fazer nada contra Zeynep; Sule convence Cengiz a deixar o local; Livre do sequestro&#8230;<\/span><\/div>\n<h2 style=\"color: #213c51;\">Resumo de segunda-feira, 09 de fevereiro<\/h2>\n<p>O amigo de Cengiz arromba a porta e encontra Sule ca\u00edda e ensanguentada. Melek se desespera, mas o homem afirma que ela s\u00f3 est\u00e1 b\u00eabada e quer saber onde Cengiz est\u00e1. No cativeiro, quando Zeynep desperta, Sinan promete proteg\u00ea\u2011la e tenta negociar a liberta\u00e7\u00e3o da esposa. Melek insiste para que Sule denuncie Cengiz, mas ela teme perder o marido. Sinan provoca Cengiz, questionando se ele teria mesmo coragem de mat\u00e1\u2011los. Cahide pensa em oferecer recompensa pelo paradeiro de Zeynep, mas Gamze sugere outra solu\u00e7\u00e3o. Melek convence Sule a ligar para a pol\u00edcia. Mas antes que isso aconte\u00e7a, Gamze entra em contato com Sule e oferece dinheiro em troca de informa\u00e7\u00f5es sobre Cengiz. Revoltada, Sule recusa a proposta. No cativeiro, Sinan e Zeynep tentam desestabilizar Cengiz, e ele insinua que dormir\u00e1 com Zeynep e a arrasta para outra sala aos gritos.<\/p>\n<h2 style=\"color: #213c51;\">Resumo de ter\u00e7a-feira, 10 de fevereiro<\/h2>\n<p>Cengiz diz para Zeynep que s\u00f3 quer que o ex-delegado sofra sabendo que a mulher est\u00e1 em suas m\u00e3os. Cahide vai \u00e0 casa de Sule, mas ela n\u00e3o abre a porta. Melek insiste para a m\u00e3e conversar com a \u201cav\u00f3\u201d, e Sule conta para a menina que a advogada armou uma farsa para fazer Zeynep acreditar que a pequena estava morta. Melek fica em choque e Cahide vai embora arrasada. Temendo por sua sa\u00fade, Cahide reorganiza seu testamento. Zeynep tenta achar uma sa\u00edda do cativeiro, mas \u00e9 recapturada por Cengiz. Melek liga para Gonul e conta sobre o amigo que emprestou o carro para Cengiz. Gonul passa a informa\u00e7\u00e3o para Ali e a pol\u00edcia vai atr\u00e1s de Il\u00e1s. Cengiz diz que deixar\u00e1 Zeynep falar com Turna antes de mat\u00e1-la e liga para Sule. Zeynep e Turna t\u00eam uma conversa comovente. Sule implora para Cengiz n\u00e3o fazer nada contra Zeynep. Abalado ao ouvir o choro do pr\u00f3prio filho, Cengiz entra em crise, desaba e telefona para sua m\u00e3e.<\/p>\n<h2 style=\"color: #213c51;\">Resumo de quarta-feira, 11 de fevereiro<\/h2>\n<p>Ap\u00f3s golpear Zeynep e deix\u00e1-la desacordada, Cengiz amea\u00e7a Sinan. Sule chega de t\u00e1xi ao galp\u00e3o, deixa Melek e Hasan esperando no carro, e entra no local atr\u00e1s de Cengiz. Ela encontra o marido prestes a cometer outro crime e implora para que ele pare. Sinan consegue se soltar, atinge Cengiz com um golpe, mas o bandido aponta a arma para Zeynep, que est\u00e1 desmaiada. Melek\/Turna chega com Hasan e, ao ver a m\u00e3e ca\u00edda, implora por sua vida. Sule usa Hasan para convencer Cengiz a n\u00e3o atirar. Ao ouvir a voz da filha, Zeynep desperta. Sule consegue fazer com que Cengiz concorde em ir embora dali. Turna permanece ao lado da m\u00e3e adotiva. Sinan corre atr\u00e1s de Cengiz e inicia uma persegui\u00e7\u00e3o. Zeynep \u00e9 levada ao hospital ao lado de Turna. Com o pequeno Hasan nos bra\u00e7os, Sule sai do carro correndo atr\u00e1s de Cengiz, e algo terr\u00edvel acontece. Cahide chega ao hospital para ver Zeynep e tem uma conversa dif\u00edcil com a filha.<\/p>\n<h2 style=\"color: #213c51;\">Resumo de quinta-feira, 12 de fevereiro<\/h2>\n<p>Todos apoiam Zeynep em um momento muito dolorido. Zeynep estranha a presen\u00e7a de Sule ali e fica surpresa com uma proposta feita pela mulher de Cengiz. Zeynep conta para Turna que elas poder\u00e3o ficar juntas, mas a menina n\u00e3o gosta de saber que ficar\u00e1 longe do irm\u00e3o. Para resolver esse problema, Zeynep reencontra Cengiz e Sule e pede que eles deixem Hasan viver com ela. O casal n\u00e3o aceita, faz uma contraproposta e os tr\u00eas chegam a um acordo. Zeynep conta para Turna que Hasan vai ficar com Sule e Cengiz, mas eles ser\u00e3o vizinhos. Zeynep explica para Cahide sobre o acordo que fez com Sule e Cengiz e, mesmo contrariada, a advogada decide ajudar a filha. Ap\u00f3s a audi\u00eancia no tribunal, Cahide entrega as chaves de uma casa para Cengiz e Sule. Turna \u00e9 r\u00edspida com Cahide e a advogada explica para a filha o motivo de a menina estar t\u00e3o fria com ela.<\/p>\n<h2 style=\"color: #213c51;\">Resumo de sexta-feira, 13 de fevereiro<\/h2>\n<p>Cahide conta para Turna e Zeynep que colocou a menina em seu testamento. Sule e Cengiz se deslumbram com a nova casa. Zeynep leva Turna para ver Hasan, mas Cengiz impede a visita. Mais tarde, a menina sai escondida da mans\u00e3o, vai \u00e0 casa de Sule e implora para ver Hasan. Turna cuida do irm\u00e3o e Cengiz se irrita ao ver a menina. Mas ele muda de postura quando a pequena fala sobre o testamento. Cengiz permite que Zeynep leve Hasan para passar a noite com a irm\u00e3. Zeynep decide passar a noite com as crian\u00e7as na casa de Gonul. Sule percebe as inten\u00e7\u00f5es do marido e os dois discutem. Zeynep tem um pesadelo e relembra um momento tr\u00e1gico de sua inf\u00e2ncia. Perturbada, ela conversa com Gonul e deixa a m\u00e3e preocupada. Intrigada, Zeynep conversa com Ali e pede que ele investigue os arquivos do inc\u00eandio que condenou Gonul no passado, e ele promete ajud\u00e1-la. Zeynep fica perturbada ao receber uma caixa com os pertences de Sinan. Ali avisa Gonul sobre o pedido feito por Zeynep e os dois arrumam uma forma de despistar a fot\u00f3grafa.<\/p>\n<h2>Saiba mais<\/h2>\n<p><a href=\"https:\/\/tvnovelas.com.br\/novelas\/resumos-de-novela-mae\/\" target=\"_blank\" rel=\"noopener\">Resumos dos cap\u00edtulos da semana&lt;c\/a&gt;<br \/>\n<\/a><a href=\"https:\/\/wp.me\/pfspD2-VN\" target=\"_blank\" rel=\"noopener\">M\u00e3e: Resgatando uma crian\u00e7a da viol\u00eancia<\/a><a href=\"https:\/\/tvnovelas.com.br\/novelas\/resumos-de-novela-mae\/\" target=\"_blank\" rel=\"noopener\"><br \/>\n<div class=\"pt-cv-wrapper\"><h2 class='pt-cv-heading-container heading2' data-blockid='759454f593'><span class='pt-cv-heading'> \u00daltimas da Novela <\/span><\/h2><div class=\"pt-cv-view pt-cv-grid pt-cv-colsys\" id=\"pt-cv-view-759454f593\"><div data-id=\"pt-cv-page-1\" class=\"pt-cv-page\" data-cvc=\"1\"><div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/www.tvnovelas.com.br\/tvnews\/mae-o-destino-final-de-melek-e-zeynep\/\" class=\"_self\" target=\"_self\" >M\u00e3e: O destino final de Melek e Zeynep<\/a><\/h4><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/www.tvnovelas.com.br\/tvnews\/mae-zeynep-enfrenta-cengiz\/\" class=\"_self\" target=\"_self\" >M\u00e3e: Zeynep enfrenta Cengiz<\/a><\/h4><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/www.tvnovelas.com.br\/tvnews\/mae-cengiz-e-preso-sob-a-acusacao-de-assassinato\/\" class=\"_self\" target=\"_self\" >M\u00e3e: Cengiz \u00e9 preso sob a acusa\u00e7\u00e3o de assassinato<\/a><\/h4><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/www.tvnovelas.com.br\/tvnews\/mae-cengiz-assina-documento-renunciando-a-guarda-dos-filhos\/\" class=\"_self\" target=\"_self\" >M\u00e3e: Cengiz assina documento renunciando \u00e0 guarda dos filhos<\/a><\/h4><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/www.tvnovelas.com.br\/tvnews\/mae-cengiz-pode-estar-com-os-dias-contados\/\" class=\"_self\" target=\"_self\" >M\u00e3e: Cengiz pode estar com os dias contados<\/a><\/h4><\/div><\/div><\/div><\/div><\/div><\/a><\/p>\n<div style=\"font-size: 120%;\"><h3>Confira tamb\u00e9m<\/h3>\r\n<a href=\"https:\/\/tvnovelas.com.br\/novelas\/\" rel=\"noopener\" target=\"_blank\"><strong>Todos os resumos de novelas<\/strong><\/a><\/br>\r\n<a href=\"https:\/\/www.tvnovelas.com.br\/tvnews\/\" rel=\"noopener\" target=\"_blank\"><strong>\u00daltimas not\u00edcias das novelas<\/strong><\/a><\/br>\r\n<a href=\"https:\/\/www.tvnovelas.com.br\/filmes\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Programa\u00e7\u00e3o de filmes na TV aberta<\/strong><\/a><\/br>\r\n<a href=\"https:\/\/caetenews.com.br\/semana\/filmes-da-globo-na-sessao-da-tarde-desta-semana\/\" target=\"_blank\" rel=\"noopener\"><strong>Confira os filmes da semana na Sess\u00e3o da Tarde<\/strong><\/a><\/br>\r\n<a href=\"https:\/\/classindportal.mj.gov.br\/consulta-filmes\" target=\"_blank\" rel=\"noopener\"><strong>Consulte a classifica\u00e7\u00e3o indicativa dos filmes e novelas<\/strong><\/a><\/br><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Em M\u00e3e nos cap\u00edtulos da semana 9 a 13\/2 &#8230; Nos pr\u00f3ximos cap\u00edtulos de M\u00e3e, Melek insiste para que Sule denuncie Cengiz, mas ela teme perder&#8230;<\/p>\n","protected":false},"author":1,"featured_media":87815,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[1012],"tags":[1013,64,14],"class_list":["post-87814","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mae","tag-mae","tag-novelas","tag-record","wpcat-1012-id"],"aioseo_notices":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.tvnovelas.com.br\/tvnews\/wp-content\/uploads\/2026\/02\/12729-1.jpg?fit=728%2C410&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/pdP2BO-mQm","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.tvnovelas.com.br\/tvnews\/wp-json\/wp\/v2\/posts\/87814","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tvnovelas.com.br\/tvnews\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tvnovelas.com.br\/tvnews\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tvnovelas.com.br\/tvnews\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tvnovelas.com.br\/tvnews\/wp-json\/wp\/v2\/comments?post=87814"}],"version-history":[{"count":1,"href":"https:\/\/www.tvnovelas.com.br\/tvnews\/wp-json\/wp\/v2\/posts\/87814\/revisions"}],"predecessor-version":[{"id":87816,"href":"https:\/\/www.tvnovelas.com.br\/tvnews\/wp-json\/wp\/v2\/posts\/87814\/revisions\/87816"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tvnovelas.com.br\/tvnews\/wp-json\/wp\/v2\/media\/87815"}],"wp:attachment":[{"href":"https:\/\/www.tvnovelas.com.br\/tvnews\/wp-json\/wp\/v2\/media?parent=87814"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tvnovelas.com.br\/tvnews\/wp-json\/wp\/v2\/categories?post=87814"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tvnovelas.com.br\/tvnews\/wp-json\/wp\/v2\/tags?post=87814"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}