{"id":90442,"date":"2026-05-12T10:10:17","date_gmt":"2026-05-12T13:10:17","guid":{"rendered":"https:\/\/www.tvnovelas.com.br\/tvnews\/?p=90442"},"modified":"2026-05-12T10:10:17","modified_gmt":"2026-05-12T13:10:17","slug":"coracao-de-mae-karsu-volta-para-a-casa-da-mae","status":"publish","type":"post","link":"https:\/\/www.tvnovelas.com.br\/tvnews\/coracao-de-mae-karsu-volta-para-a-casa-da-mae\/","title":{"rendered":"Cora\u00e7\u00e3o de M\u00e3e: Karsu volta para a casa da m\u00e3e"},"content":{"rendered":"<p>Cora\u00e7\u00e3o de M\u00e3e: Karsu volta para a casa da m\u00e3e<\/p>\n<figure id=\"attachment_90443\" aria-describedby=\"caption-attachment-90443\" style=\"width: 728px\" class=\"wp-caption alignnone\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"wp-image-90443 size-full\" title=\"(Foto: Record TV\/Cora\u00e7\u00e3o de M\u00e3e)\" src=\"https:\/\/i0.wp.com\/www.tvnovelas.com.br\/tvnews\/wp-content\/uploads\/2026\/05\/13250.jpg?resize=728%2C409&#038;ssl=1\" alt=\"Foto em Cora\u00e7\u00e3o de M\u00e3e: Karsu volta para a casa da m\u00e3e\" width=\"728\" height=\"409\" srcset=\"https:\/\/i0.wp.com\/www.tvnovelas.com.br\/tvnews\/wp-content\/uploads\/2026\/05\/13250.jpg?w=728&amp;ssl=1 728w, https:\/\/i0.wp.com\/www.tvnovelas.com.br\/tvnews\/wp-content\/uploads\/2026\/05\/13250.jpg?resize=250%2C140&amp;ssl=1 250w\" sizes=\"(max-width: 728px) 100vw, 728px\" \/><figcaption id=\"caption-attachment-90443\" class=\"wp-caption-text\">Cora\u00e7\u00e3o de M\u00e3e: Karsu volta para a casa da m\u00e3e<\/figcaption><\/figure>\n<p>Em Cora\u00e7\u00e3o de M\u00e3e, nesta ter\u00e7a, dia 12, Ap\u00f3s acompanhar Reha no hospital, Karsu revela que assistiu ao v\u00eddeo e descobriu toda a verdade sobre a arma\u00e7\u00e3o dele, e volta para a casa da m\u00e3e. Ela tamb\u00e9m retorna \u00e0 Livraria e investe suas energias para se reconciliar com Atilla. Do outro lado, Reha e Hande voltam a morar juntos e ele promete se casar com ela.<\/p>\n<p>Enquanto isto, Hasan come\u00e7a a enfrentar as consequ\u00eancias por ter abandonado a m\u00e1fia, ao mesmo tempo em quepede uma nova chance para Filiz e est\u00e1 decidido a se redimir com Karsu. Neste caso, ele vai enfrentar um contratempo: m antigo rival sequestra Deniz para pressionar Hasan e Atilla, e eles precisar\u00e3o se envolver novamente com a m\u00e1fia para proteger o pequeno.<\/p>\n<h2 style=\"color: #8a5f41;\">Resumo de ter\u00e7a-feira, 12 de maio<\/h2>\n<p>Hasan come\u00e7a a enfrentar as consequ\u00eancias por ter abandonado a m\u00e1fia. Ap\u00f3s acompanhar Reha no hospital, Karsu revela que assistiu ao v\u00eddeo e descobriu toda a verdade, e volta para a casa da m\u00e3e. Hasan tem uma conversa tensa com o marido de sua funcion\u00e1ria e faz exig\u00eancias ao homem. Filiz consegue um comprador para suas casas. A pedido de Hasan, Omer come\u00e7a a trabalhar com a m\u00e1fia. Karsu retorna \u00e0 livraria e sente ci\u00fames ao observar Atilla conversando com outra mulher. Reha cogita voltar a morar com Hande. Hasan tenta se reaproximar de Atilla. Lale surpreende Filiz ao dizer que \u00e9 a nova s\u00edndica do condom\u00ednio. Enquanto Karsu pede desculpas para Atilla. Hande volta a morar com Reha e ele promete se casar com ela. Hasan pede uma nova chance para Filiz e est\u00e1 decidido a se redimir com Karsu. A ex-s\u00edndica do Recanto do Para\u00edso coloca em pr\u00e1tica um plano para se vingar de Lale e reconquistar seu cargo. Karsu investe suas energias para se reconciliar com Atilla. Um antigo rival sequestra Deniz para pressionar Hasan e Atilla, e eles precisar\u00e3o se envolver novamente com a m\u00e1fia para proteger o pequeno.<br \/>\n<!--FIM--><\/p>\n<h2>Saiba mais<\/h2>\n<p><a href=\"https:\/\/tvnovelas.com.br\/novelas\/resumos-de-coracao-de-mae\/\" target=\"_blank\" rel=\"noopener\">Resumos dos cap\u00edtulos da semana de Cora\u00e7\u00e3o de M\u00e3e<\/a><br \/>\n<div class=\"pt-cv-wrapper\"><h1 class='pt-cv-heading-container heading2' data-blockid='dc296283li'><span class='pt-cv-heading'> \u00daltimas da novela <\/span><\/h1><div class=\"pt-cv-view pt-cv-grid pt-cv-colsys\" id=\"pt-cv-view-dc296283li\"><div data-id=\"pt-cv-page-1\" class=\"pt-cv-page\" data-cvc=\"1\"><div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/www.tvnovelas.com.br\/tvnews\/coracao-de-mae-karsu-confronta-atilla\/\" class=\"_self\" target=\"_self\" >Cora\u00e7\u00e3o de M\u00e3e: Karsu confronta Atilla<\/a><\/h4><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/www.tvnovelas.com.br\/tvnews\/coracao-de-mae-karsu-completa-vinganca-e-abandona-reha\/\" class=\"_self\" target=\"_self\" >Cora\u00e7\u00e3o de M\u00e3e: Karsu completa vingan\u00e7a e abandona Reha<\/a><\/h4><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/www.tvnovelas.com.br\/tvnews\/coracao-de-mae-karsu-volta-para-a-casa-da-mae\/\" class=\"_self\" target=\"_self\" >Cora\u00e7\u00e3o de M\u00e3e: Karsu volta para a casa da m\u00e3e<\/a><\/h4><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/www.tvnovelas.com.br\/tvnews\/coracao-de-mae-karsu-decide-voltar-a-morar-com-reha\/\" class=\"_self\" target=\"_self\" >Cora\u00e7\u00e3o de M\u00e3e: Karsu decide voltar a morar com Reha<\/a><\/h4><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/www.tvnovelas.com.br\/tvnews\/coracao-de-mae-deniz-e-sequestrado-em-acao-da-mafia\/\" class=\"_self\" target=\"_self\" >Em Cora\u00e7\u00e3o de M\u00e3e: Deniz \u00e9 sequestrado em a\u00e7\u00e3o da m\u00e1fia<\/a><\/h4><\/div><\/div><\/div><\/div><\/div><br \/>\n<strong>Talvez voc\u00ea se interesse tamb\u00e9m<\/strong><br \/>\n<a href=\"https:\/\/pt.wikipedia.org\/wiki\/Sand%C4%B1k_Kokusu\">Cora\u00e7\u00e3o de M\u00e3e, na Wikipedia<\/a><br \/>\n<a href=\"https:\/\/classindportal.mj.gov.br\/consulta-filmes\" target=\"_blank\" rel=\"noopener\">Consulte a classifica\u00e7\u00e3o indicativa das novelas<\/a><\/p>\n<div style=\"font-size: 120%;\"><h3>Confira tamb\u00e9m<\/h3>\r\n<a href=\"https:\/\/tvnovelas.com.br\/novelas\/\" rel=\"noopener\" target=\"_blank\"><strong>Todos os resumos de novelas<\/strong><\/a><\/br>\r\n<a href=\"https:\/\/www.tvnovelas.com.br\/tvnews\/\" rel=\"noopener\" target=\"_blank\"><strong>\u00daltimas not\u00edcias das novelas<\/strong><\/a><\/br>\r\n<a href=\"https:\/\/www.tvnovelas.com.br\/filmes\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Programa\u00e7\u00e3o de filmes na TV aberta<\/strong><\/a><\/br>\r\n<a href=\"https:\/\/caetenews.com.br\/semana\/filmes-da-globo-na-sessao-da-tarde-desta-semana\/\" target=\"_blank\" rel=\"noopener\"><strong>Confira os filmes da semana na Sess\u00e3o da Tarde<\/strong><\/a><\/br>\r\n<a href=\"https:\/\/classindportal.mj.gov.br\/consulta-filmes\" target=\"_blank\" rel=\"noopener\"><strong>Consulte a classifica\u00e7\u00e3o indicativa dos filmes e novelas<\/strong><\/a><\/br><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Cora\u00e7\u00e3o de M\u00e3e: Karsu volta para a casa da m\u00e3e&#8230;. Em Cora\u00e7\u00e3o de M\u00e3e, nesta ter\u00e7a, dia 12, Ap\u00f3s acompanhar Reha no hospital, Karsu revela que assistiu ao v\u00eddeo&#8230;<\/p>\n","protected":false},"author":1,"featured_media":90443,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[1049],"tags":[1048,64,14],"class_list":["post-90442","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coracao-de-mae","tag-coracao-de-mae","tag-novelas","tag-record","wpcat-1049-id"],"aioseo_notices":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.tvnovelas.com.br\/tvnews\/wp-content\/uploads\/2026\/05\/13250.jpg?fit=728%2C409&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/pdP2BO-nwK","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.tvnovelas.com.br\/tvnews\/wp-json\/wp\/v2\/posts\/90442","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tvnovelas.com.br\/tvnews\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tvnovelas.com.br\/tvnews\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tvnovelas.com.br\/tvnews\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tvnovelas.com.br\/tvnews\/wp-json\/wp\/v2\/comments?post=90442"}],"version-history":[{"count":1,"href":"https:\/\/www.tvnovelas.com.br\/tvnews\/wp-json\/wp\/v2\/posts\/90442\/revisions"}],"predecessor-version":[{"id":90444,"href":"https:\/\/www.tvnovelas.com.br\/tvnews\/wp-json\/wp\/v2\/posts\/90442\/revisions\/90444"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tvnovelas.com.br\/tvnews\/wp-json\/wp\/v2\/media\/90443"}],"wp:attachment":[{"href":"https:\/\/www.tvnovelas.com.br\/tvnews\/wp-json\/wp\/v2\/media?parent=90442"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tvnovelas.com.br\/tvnews\/wp-json\/wp\/v2\/categories?post=90442"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tvnovelas.com.br\/tvnews\/wp-json\/wp\/v2\/tags?post=90442"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}