{"id":90458,"date":"2026-05-13T09:31:53","date_gmt":"2026-05-13T12:31:53","guid":{"rendered":"https:\/\/www.tvnovelas.com.br\/tvnews\/?p=90458"},"modified":"2026-05-13T09:31:53","modified_gmt":"2026-05-13T12:31:53","slug":"a-nobreza-do-amor-jendal-cai-no-golpe-de-imani","status":"publish","type":"post","link":"https:\/\/www.tvnovelas.com.br\/tvnews\/a-nobreza-do-amor-jendal-cai-no-golpe-de-imani\/","title":{"rendered":"A Nobreza do Amor: Jendal cai no golpe de Imani"},"content":{"rendered":"<figure id=\"attachment_90459\" aria-describedby=\"caption-attachment-90459\" style=\"width: 728px\" class=\"wp-caption alignnone\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"wp-image-90459 size-full\" title=\"(Foto: TV Globo\/A Nobreza do Amor)\" src=\"https:\/\/i0.wp.com\/www.tvnovelas.com.br\/tvnews\/wp-content\/uploads\/2026\/05\/13254.jpg?resize=728%2C411&#038;ssl=1\" alt=\"Foto em A Nobreza do Amor: Jendal cai no golpe de Imani\" width=\"728\" height=\"411\" srcset=\"https:\/\/i0.wp.com\/www.tvnovelas.com.br\/tvnews\/wp-content\/uploads\/2026\/05\/13254.jpg?w=728&amp;ssl=1 728w, https:\/\/i0.wp.com\/www.tvnovelas.com.br\/tvnews\/wp-content\/uploads\/2026\/05\/13254.jpg?resize=250%2C141&amp;ssl=1 250w\" sizes=\"(max-width: 728px) 100vw, 728px\" \/><figcaption id=\"caption-attachment-90459\" class=\"wp-caption-text\">A Nobreza do Amor: Jendal cai no golpe de Imani<\/figcaption><\/figure>\n<p>Em A Nobreza do Amor, quem v\u00ea Jendal (L\u00e1zaro Ramos) governando com m\u00e3o de ferro n\u00e3o imagina o qu\u00e3o f\u00e1cil \u00e9 manipul\u00e1-lo atrav\u00e9s do ego. O usurpador ser\u00e1 v\u00edtima de um plano ardiloso arquitetado por Imani (Dhara Lopes) e o mercen\u00e1rio Pascoal (Luciano Quirino). O objetivo da dupla? Arrancar o m\u00e1ximo de dinheiro poss\u00edvel do &#8220;rei vaidoso&#8221;.<\/p>\n<p>Ap\u00f3s passarem a noite juntos, Imani colocar\u00e1 em pr\u00e1tica a segunda fase do plano. Enquanto Jendal dorme, ela se encontra sorrateiramente com Pascoal para celebrar o sucesso da sedu\u00e7\u00e3o. \u201cO rei caiu direitinho na minha conversa\u201d, comemorar\u00e1 a impostora, sendo aplaudida pelo c\u00famplice.<\/p>\n<p>Ao acordar, Jendal encontrar\u00e1 uma Imani &#8220;triste&#8221;, simulando que est\u00e1 indo embora para se entregar ao seu &#8220;dono&#8221; e pagar d\u00edvidas de viagem. Com um discurso ensaiado, ela dar\u00e1 um beijo de despedida no monarca, deixando-o exatamente onde ela queria: com o desejo de possu\u00ed-la permanentemente.<\/p>\n<p>Na sala do trono, o teatro continuar\u00e1. Pascoal fingir\u00e1 que est\u00e1 levando a &#8220;impostora&#8221; embora, pedindo perd\u00e3o por ter decepcionado o rei. \u00c9 nesse momento que Jendal, cego pela necessidade de ter uma &#8220;Alika&#8221; sob seu controle, morder\u00e1 a isca.<\/p>\n<p>\u201cEspere! De quanto \u00e9 a d\u00edvida feita por Imani? Quero que ela permane\u00e7a aqui nesse pal\u00e1cio, sob a minha prote\u00e7\u00e3o\u201d, decretar\u00e1 o rei, ignorando os avisos de sua filha.<\/p>\n<p>Sentindo o cheiro de lucro, Pascoal n\u00e3o perder\u00e1 a chance de inflar o valor. Ele pedir\u00e1 nada menos que a metade do valor da recompensa original pela verdadeira princesa, alegando custos de viagem e &#8220;lucros cessantes&#8221;.<\/p>\n<p>\u201cPap\u00e1, isso \u00e9 um absurdo!\u201d, gritar\u00e1 a princesa, sendo prontamente calada pelo pai. Jendal n\u00e3o s\u00f3 aceitar\u00e1 o valor exorbitante como convidar\u00e1 o golpista para se hospedar no pal\u00e1cio enquanto o tesouro \u00e9 providenciado.<\/p>\n<p>A decis\u00e3o do monarca deixar\u00e1 K\u00eania (Nikolly Fernandes) e Chinua (Hilton Cobra) em choque.<br \/>\n<!--FIM--><br \/>\n<a href=\"https:\/\/tvnovelas.com.br\/novelas\/resumos-de-a-nobreza-do-amor\/ \" target=\"_blank\" rel=\"noopener\">Resumos dos cap\u00edtulos de A Nobreza do Amor<\/a><br \/>\n<div class=\"pt-cv-wrapper\"><h1 class='pt-cv-heading-container heading2' data-blockid='8cc3dc07f4'><span class='pt-cv-heading'> \u00daltimas da novela <\/span><\/h1><div class=\"pt-cv-view pt-cv-grid pt-cv-colsys\" id=\"pt-cv-view-8cc3dc07f4\"><div data-id=\"pt-cv-page-1\" class=\"pt-cv-page\" data-cvc=\"1\"><div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/www.tvnovelas.com.br\/tvnews\/a-nobreza-do-amor-jendal-cai-no-golpe-de-imani\/\" class=\"_blank\" target=\"_blank\" >A Nobreza do Amor: Jendal cai no golpe de Imani<\/a><\/h4><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/www.tvnovelas.com.br\/tvnews\/a-nobreza-do-amor-jendal-promete-casamento-arranjado-a-kenia\/\" class=\"_blank\" target=\"_blank\" >A Nobreza do Amor: Jendal promete casamento arranjado a K\u00eania<\/a><\/h4><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/www.tvnovelas.com.br\/tvnews\/a-nobreza-do-amor-jendal-surpreende-ao-poupar-dumi-da-morte\/\" class=\"_blank\" target=\"_blank\" >A Nobreza do Amor: Jendal surpreende ao poupar Dumi da morte<\/a><\/h4><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/www.tvnovelas.com.br\/tvnews\/o-que-se-passa-em-a-nobreza-do-amor-na-semana-11-a-16-5\/\" class=\"_blank\" target=\"_blank\" >O que se passa em A Nobreza do Amor na semana 11 a 16\/5<\/a><\/h4><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/www.tvnovelas.com.br\/tvnews\/a-nobreza-do-amor-mirinho-arma-emboscada-para-impressionar-alika\/\" class=\"_blank\" target=\"_blank\" >A Nobreza do Amor: Mirinho arma emboscada para impressionar Alika<\/a><\/h4><\/div><\/div><\/div><\/div><\/div><\/p>\n<div style=\"font-size: 120%;\"><h3>Confira tamb\u00e9m<\/h3>\r\n<a href=\"https:\/\/tvnovelas.com.br\/novelas\/\" rel=\"noopener\" target=\"_blank\"><strong>Todos os resumos de novelas<\/strong><\/a><\/br>\r\n<a href=\"https:\/\/www.tvnovelas.com.br\/tvnews\/\" rel=\"noopener\" target=\"_blank\"><strong>\u00daltimas not\u00edcias das novelas<\/strong><\/a><\/br>\r\n<a href=\"https:\/\/www.tvnovelas.com.br\/filmes\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Programa\u00e7\u00e3o de filmes na TV aberta<\/strong><\/a><\/br>\r\n<a href=\"https:\/\/caetenews.com.br\/semana\/filmes-da-globo-na-sessao-da-tarde-desta-semana\/\" target=\"_blank\" rel=\"noopener\"><strong>Confira os filmes da semana na Sess\u00e3o da Tarde<\/strong><\/a><\/br>\r\n<a href=\"https:\/\/classindportal.mj.gov.br\/consulta-filmes\" target=\"_blank\" rel=\"noopener\"><strong>Consulte a classifica\u00e7\u00e3o indicativa dos filmes e novelas<\/strong><\/a><\/br><\/div>\n<h2>Sobre a novela:<\/h2>\n<p><a href=\"https:\/\/tvnovelas.com.br\/page2\/arquivo\/a-nobreza-do-amor-a-conexao-brasil-africa\/\" target=\"_blank\" rel=\"noopener\">A Nobreza do Amor: A conex\u00e3o Brasil-\u00c1frica<\/a> (Sinopse)<br \/>\n<a href=\"https:\/\/pt.wikipedia.org\/wiki\/A_Nobreza_do_Amor\" target=\"_blank\" rel=\"noopener\">Sobre A Nobreza do Amor, na Wikipedia<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Nobreza do Amor: Jendal cai no golpe de Imani&#8230; Quem v\u00ea Jendal governando com m\u00e3o de ferro n\u00e3o imagina o qu\u00e3o f\u00e1cil \u00e9 manipul\u00e1-lo atrav\u00e9s&#8230;<\/p>\n","protected":false},"author":1,"featured_media":90459,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","_wp_rev_ctl_limit":""},"categories":[1063],"tags":[1064,5,64],"class_list":["post-90458","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-a-nobreza-do-amor","tag-a-nobreza-do-amor","tag-globo","tag-novelas","wpcat-1063-id"],"aioseo_notices":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.tvnovelas.com.br\/tvnews\/wp-content\/uploads\/2026\/05\/13254.jpg?fit=728%2C411&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/pdP2BO-nx0","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.tvnovelas.com.br\/tvnews\/wp-json\/wp\/v2\/posts\/90458","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tvnovelas.com.br\/tvnews\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tvnovelas.com.br\/tvnews\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tvnovelas.com.br\/tvnews\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tvnovelas.com.br\/tvnews\/wp-json\/wp\/v2\/comments?post=90458"}],"version-history":[{"count":1,"href":"https:\/\/www.tvnovelas.com.br\/tvnews\/wp-json\/wp\/v2\/posts\/90458\/revisions"}],"predecessor-version":[{"id":90460,"href":"https:\/\/www.tvnovelas.com.br\/tvnews\/wp-json\/wp\/v2\/posts\/90458\/revisions\/90460"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tvnovelas.com.br\/tvnews\/wp-json\/wp\/v2\/media\/90459"}],"wp:attachment":[{"href":"https:\/\/www.tvnovelas.com.br\/tvnews\/wp-json\/wp\/v2\/media?parent=90458"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tvnovelas.com.br\/tvnews\/wp-json\/wp\/v2\/categories?post=90458"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tvnovelas.com.br\/tvnews\/wp-json\/wp\/v2\/tags?post=90458"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}