{"id":90658,"date":"2026-05-23T09:50:49","date_gmt":"2026-05-23T12:50:49","guid":{"rendered":"https:\/\/www.tvnovelas.com.br\/tvnews\/?p=90658"},"modified":"2026-05-23T10:01:23","modified_gmt":"2026-05-23T13:01:23","slug":"o-que-rola-em-a-nobreza-do-amor-na-semana-25-a-30-5","status":"publish","type":"post","link":"https:\/\/www.tvnovelas.com.br\/tvnews\/o-que-rola-em-a-nobreza-do-amor-na-semana-25-a-30-5\/","title":{"rendered":"O que rola em A Nobreza do Amor na semana 25 a 30\/5"},"content":{"rendered":"<div style=\"background-color: #f1e2d1; border-style: solid; border-width: 0px 0px 10px 0px; solid green; border-radius: 30px; padding: 10px; font-size: 125%; text-align: justify;\">.<\/p>\n<p><figure id=\"attachment_90659\" aria-describedby=\"caption-attachment-90659\" style=\"width: 728px\" class=\"wp-caption aligncenter\"><img data-recalc-dims=\"1\" decoding=\"async\" class=\"wp-image-90659 size-full\" title=\"(Foto: TV Globo\/A Nobreza do Amor)\" src=\"https:\/\/i0.wp.com\/www.tvnovelas.com.br\/tvnews\/wp-content\/uploads\/2026\/05\/13288.jpg?resize=728%2C414&#038;ssl=1\" alt=\"Foto erm O que rola em A Nobreza do Amor na semana 25 a 30\/5\" width=\"728\" height=\"414\" srcset=\"https:\/\/i0.wp.com\/www.tvnovelas.com.br\/tvnews\/wp-content\/uploads\/2026\/05\/13288.jpg?w=728&amp;ssl=1 728w, https:\/\/i0.wp.com\/www.tvnovelas.com.br\/tvnews\/wp-content\/uploads\/2026\/05\/13288.jpg?resize=250%2C142&amp;ssl=1 250w\" sizes=\"(max-width: 728px) 100vw, 728px\" \/><figcaption id=\"caption-attachment-90659\" class=\"wp-caption-text\">O que rola em A Nobreza do Amor na semana 25 a 30\/5<\/figcaption><\/figure><br \/>\n<strong style=\"color: #810b38; font-size: 120%;\">Nos pr\u00f3ximos cap\u00edtulos de A Nobreza do Amor, <\/strong><span style=\"color: #810b38; font-size: 120%;\">Jendal manda por fogo nas doa\u00e7\u00f5es recebidas da Dinamarca; Os rebeldes saqueiam a comida do pal\u00e1cio, e Jendal se revolta; K\u00eania e Chinua se assustam com a f\u00faria de Jendal contra o povo; Virg\u00ednia flagra Mirinho com Alika\/L\u00facia; Dumi confessa seu amor por K\u00eania, e os dois se beijam&#8230;<\/span><\/div>\n<h2 style=\"color: #810b38;\">Resumo de segunda-feira, 25 de maio<\/h2>\n<p>Marta repreende os ataques de Virg\u00ednia a Alika\/L\u00facia. Eust\u00e1quio e Eug\u00eania garantem que divulgar\u00e3o o ateli\u00ea de Alika\/L\u00facia e Teresa. Tonho avisa a Casemiro sobre o estado de sa\u00fade dos trabalhadores do engenho, e convoca Onildo. D\u00f4ra sugere promover um desfile de moda no Gr\u00eamio Recreativo, a fim de divulgar a cidade e o ateli\u00ea de Alika\/L\u00facia. Mr.Campbell alerta Jendal para a desconfian\u00e7a internacional sobre Batanga. Ladisa informa Dumi sobre a ofensiva de Pascoal contra a popula\u00e7\u00e3o. Onildo garante que os trabalhadores est\u00e3o com mal\u00e1ria. Virg\u00ednia pensa em como prejudicar o desfile que ajudar\u00e1 Alika\/L\u00facia. Chinua anuncia a chegada de donativos dinamarqueses para a popula\u00e7\u00e3o de Batanga. Belmira flagra Viriato com Carrapato. Jendal ordena que Pascoal ateie fogo \u00e0s doa\u00e7\u00f5es recebidas da Dinamarca.<\/p>\n<h2 style=\"color: #810b38;\">Resumo de ter\u00e7a-feira, 26 de maio<\/h2>\n<p>K\u00eania sofre com a a\u00e7\u00e3o de Jendal, e acredita ter visto Dumi entre os populares. Belmira descobre que seu pai \u00e9 um cangaceiro. Alika declara seu orgulho pelas a\u00e7\u00f5es de Tonho. Gra\u00e7a aconselha Mirinho a se aproximar de Di\u00f3genes e conseguir um espa\u00e7o no banco. Virg\u00ednia engana Marta para prejudicar Alika\/L\u00facia. Akin, Dumi e Ladisa planejam como se livrar de Pascoal. Fortunato convoca Di\u00f3genes, Casemiro e Mirinho \u00e0 delegacia e anuncia que Fabr\u00edcio \u00e9 um golpista. Virg\u00ednia se oferece a Alika\/L\u00facia como modelo da sua marca. Liderados por Akin, Dumi e Ladisa, os rebeldes saqueiam a comida do pal\u00e1cio, e Jendal se revolta.<\/p>\n<h2 style=\"color: #810b38;\">Resumo de quarta-feira, 27 de maio<\/h2>\n<p>K\u00eania e Chinua se assustam com a f\u00faria de Jendal contra o povo. Alika\/L\u00facia desconfia das inten\u00e7\u00f5es de Virg\u00ednia ao pedir para representar seu ateli\u00ea. Mirinho explica como foi enganado por Fabr\u00edcio. K\u00eania n\u00e3o acredita quando Chinua diz n\u00e3o saber de Dumi. Viriato percebe que Belmira est\u00e1 se aproximando de Carrapato. Virg\u00ednia confessa a Sebasti\u00e3o que deseja se vingar de Alika\/L\u00facia. Mirinho pede um emprego a Di\u00f3genes no banco. Niara\/Vera e Maria Helena incentivam as crian\u00e7as a estudar na nova escola, enquanto Alika\/L\u00facia e Teresa convocam todas as mulheres a desfilar no Gr\u00eamio. K\u00eania se entristece com a mis\u00e9ria do povo em Batanga. Dumi e K\u00eania se encontram.<\/p>\n<h2 style=\"color: #810b38;\">Resumo de quinta-feira, 28 de maio<\/h2>\n<p>K\u00eania disfar\u00e7a a presen\u00e7a de Dumi na frente de Pascoal. Dumi afirma a Akin que K\u00eania o salvou. Tonho e Janu\u00e1rio se preocupam com a sa\u00fade de todos no engenho. Dumi pede que Chinua o leve para falar com K\u00eania. Miguel afirma que permitir\u00e1 que Salma desfile no Gr\u00eamio caso Fuad concorde. Viriato conversa com Carrapato sobre Belmira. Onildo sonda Niara\/Vera ao comentar o artigo de Nilo Pe\u00e7anha denunciando o golpe em Batanga. Omar escreve para Alika. Omar e Burak enfrentam uma tempestade em alto-mar. Virg\u00ednia flagra Mirinho com Alika\/L\u00facia. Chinua leva Dumi ao encontro de K\u00eania.<\/p>\n<h2 style=\"color: #810b38;\">Resumo de sexta-feira, 29 de maio<\/h2>\n<p>Dumi confessa seu amor por K\u00eania, e os dois se beijam. Virg\u00ednia tenta disfar\u00e7ar seu inc\u00f4modo diante de Mirinho e Alika\/L\u00facia.Fortunato humilha Maria Helena. Mirinho confirma a Virg\u00ednia que aceitar\u00e1 o emprego como caixa de banco oferecido por Di\u00f3genes. Belmira se assusta com as hist\u00f3rias contadas pelo pai, e Viriato se penaliza. Dumi consegue se esconder quando Jendal se aproxima do quarto de K\u00eania. Omar planeja chegar ao Brasil em breve. Niara comenta com Teresa e Alika que acredita que Onildo desconfie da identidade das duas. Robert se apresenta a Jendal.<\/p>\n<h2 style=\"color: #810b38;\">Resumo de s\u00e1bado, 30 de maio<\/h2>\n<p>Robert diz a Jendal que deseja fazer uma reportagem sobre Batanga. K\u00eania se preocupa com as inten\u00e7\u00f5es de Robert. Tonho se une a Casemiro e Onildo para confrontar Bart\u00f4 em nome da popula\u00e7\u00e3o de Barro Preto, e Alika sente orgulho do amado. K\u00eania questiona Chinua sobre o envolvimento de Dumi com os rebeldes. Di\u00f3genes recebe Mirinho no banco, e promove Manoel a seu chefe. Carrapato revela a Belmira que voltou para lhe buscar, e Viriato se preocupa. Disfar\u00e7ado, Dumi afirma a Robert que Jendal \u00e9 um golpista. Com a ajuda de Pascoal, Jendal conduz Robert ao po\u00e7o das serpentes.<br \/>\n<!--FIM--><br \/>\n<a href=\"https:\/\/tvnovelas.com.br\/novelas\/resumos-de-a-nobreza-do-amor\/ \" target=\"_blank\" rel=\"noopener\">Resumos dos cap\u00edtulos de A Nobreza do Amor<\/a><br \/>\n<div class=\"pt-cv-wrapper\"><h1 class=\"pt-cv-heading-container heading2\" data-blockid=\"8cc3dc07f4\"><span class=\"pt-cv-heading\"> \u00daltimas da novela <\/span><\/h1><div class=\"pt-cv-view pt-cv-grid pt-cv-colsys\" id=\"pt-cv-view-8cc3dc07f4\"><div data-id=\"pt-cv-page-1\" class=\"pt-cv-page\" data-cvc=\"1\"><div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/www.tvnovelas.com.br\/tvnews\/a-nobreza-do-amor-tonho-reage-e-se-salva-da-morte\/\" class=\"_blank\" target=\"_blank\" >A Nobreza do Amor: Tonho reage e se salva da morte<\/a><\/h4><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/www.tvnovelas.com.br\/tvnews\/a-nobreza-do-amor-mirinho-sabota-remedios-de-tonho\/\" class=\"_blank\" target=\"_blank\" >A Nobreza do Amor: Mirinho sabota rem\u00e9dios de Tonho<\/a><\/h4><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/www.tvnovelas.com.br\/tvnews\/o-que-rola-em-a-nobreza-do-amor-na-semana-6-a-11-7\/\" class=\"_blank\" target=\"_blank\" >O que rola em A Nobreza do Amor na semana 6 a 11\/7<\/a><\/h4><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/www.tvnovelas.com.br\/tvnews\/a-nobreza-do-amor-mirinho-dira-que-nao-deseja-morte-de-tonho\/\" class=\"_blank\" target=\"_blank\" >A Nobreza do Amor: Mirinho dir\u00e1 que n\u00e3o deseja morte de Tonho<\/a><\/h4><\/div><\/div>\n<div class=\"col-md-12 col-sm-12 col-xs-12 pt-cv-content-item pt-cv-1-col\" ><div class='pt-cv-ifield'><h4 class=\"pt-cv-title\"><a href=\"https:\/\/www.tvnovelas.com.br\/tvnews\/a-nobreza-do-amor-hoje22-mirinho-sabota-o-medicamento-de-tonho\/\" class=\"_blank\" target=\"_blank\" >A Nobreza do Amor, hoje(23\/6): Mirinho sabota o medicamento de Tonho<\/a><\/h4><\/div><\/div><\/div><\/div><\/div><\/p>\n<div style=\"font-size: 120%;\"><h3>Confira tamb\u00e9m<\/h3>\r\n<a href=\"https:\/\/tvnovelas.com.br\/novelas\/\" rel=\"noopener\" target=\"_blank\"><strong>Todos os resumos de novelas<\/strong><\/a><\/br>\r\n<a href=\"https:\/\/www.tvnovelas.com.br\/tvnews\/\" rel=\"noopener\" target=\"_blank\"><strong>\u00daltimas not\u00edcias das novelas<\/strong><\/a><\/br>\r\n<a href=\"https:\/\/www.tvnovelas.com.br\/filmes\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Programa\u00e7\u00e3o de filmes na TV aberta<\/strong><\/a><\/br>\r\n<a href=\"https:\/\/caetenews.com.br\/semana\/filmes-da-globo-na-sessao-da-tarde-desta-semana\/\" target=\"_blank\" rel=\"noopener\"><strong>Confira os filmes da semana na Sess\u00e3o da Tarde<\/strong><\/a><\/br>\r\n<a href=\"https:\/\/classindportal.mj.gov.br\/consulta-filmes\" target=\"_blank\" rel=\"noopener\"><strong>Consulte a classifica\u00e7\u00e3o indicativa dos filmes e novelas<\/strong><\/a><\/br><\/div>\n<h2>Sobre a novela:<\/h2>\n<p><a href=\"https:\/\/tvnovelas.com.br\/page2\/arquivo\/a-nobreza-do-amor-a-conexao-brasil-africa\/\" target=\"_blank\" rel=\"noopener\">A Nobreza do Amor: A conex\u00e3o Brasil-\u00c1frica<\/a> (Sinopse)<br \/>\n<a href=\"https:\/\/pt.wikipedia.org\/wiki\/A_Nobreza_do_Amor\" target=\"_blank\" rel=\"noopener\">Sobre A Nobreza do Amor, na Wikipedia<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O que rola em A Nobreza do Amor na semana 25 a 30\/5&#8230; Jendal manda por fogo nas doa\u00e7\u00f5es recebidas da Dinamarca; Os rebeldes saqueiam&#8230;<\/p>\n","protected":false},"author":1,"featured_media":90659,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false,"_wp_rev_ctl_limit":""},"categories":[1063],"tags":[1064,5,64],"class_list":["post-90658","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-a-nobreza-do-amor","tag-a-nobreza-do-amor","tag-globo","tag-novelas","wpcat-1063-id"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 4.9.10 - aioseo.com -->\n\t<meta name=\"description\" content=\"O que rola em A Nobreza do Amor na semana 25 a 30\/5... Jendal manda por fogo nas doa\u00e7\u00f5es recebidas da Dinamarca; Os rebeldes saqueiam...\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Paulo Antonio\"\/>\n\t<meta name=\"google-site-verification\" content=\"rkK9U9oF3S28qRc6gTV5lXAuAQX2mzrSuD6qnebspv8\" \/>\n\t<meta name=\"msvalidate.01\" content=\"AD79AA3D776A998E190189FA8E4A5338\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.tvnovelas.com.br\/tvnews\/o-que-rola-em-a-nobreza-do-amor-na-semana-25-a-30-5\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 4.9.10\" \/>\n\t\t<meta property=\"og:locale\" content=\"pt_BR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"TV News\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"O que rola em A Nobreza do Amor na semana 25 a 30\/5 - TV News\" \/>\n\t\t<meta property=\"og:description\" content=\"O que rola em A Nobreza do Amor na semana 25 a 30\/5... Jendal manda por fogo nas doa\u00e7\u00f5es recebidas da Dinamarca; Os rebeldes saqueiam...\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.tvnovelas.com.br\/tvnews\/o-que-rola-em-a-nobreza-do-amor-na-semana-25-a-30-5\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/www.tvnovelas.com.br\/tvshow\/wp-content\/uploads\/2018\/07\/tvnovelas_logo.jpg\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/www.tvnovelas.com.br\/tvshow\/wp-content\/uploads\/2018\/07\/tvnovelas_logo.jpg\" \/>\n\t\t<meta property=\"article:tag\" content=\"a nobreza do amor\" \/>\n\t\t<meta property=\"article:tag\" content=\"globo\" \/>\n\t\t<meta property=\"article:tag\" content=\"novelas\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2026-05-23T12:50:49+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-05-23T13:01:23+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tevenovelas\/\" \/>\n\t\t<meta property=\"article:author\" content=\"https:\/\/facebook.com\/pauloantonyo\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:site\" content=\"@TVNovelas\" \/>\n\t\t<meta name=\"twitter:title\" content=\"O que rola em A Nobreza do Amor na semana 25 a 30\/5 - TV News\" \/>\n\t\t<meta name=\"twitter:description\" content=\"O que rola em A Nobreza do Amor na semana 25 a 30\/5... Jendal manda por fogo nas doa\u00e7\u00f5es recebidas da Dinamarca; Os rebeldes saqueiam...\" \/>\n\t\t<meta name=\"twitter:creator\" content=\"@TVNovelas\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/www.tvnovelas.com.br\/tvshow\/wp-content\/uploads\/2018\/07\/tvnovelas_logo.jpg\" \/>\n\t\t<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t\t<meta name=\"twitter:data1\" content=\"Paulo Antonio\" \/>\n\t\t<meta name=\"twitter:label2\" content=\"Tempo de leitura estimado\" \/>\n\t\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tvnovelas.com.br\\\/tvnews\\\/o-que-rola-em-a-nobreza-do-amor-na-semana-25-a-30-5\\\/#article\",\"name\":\"O que rola em A Nobreza do Amor na semana 25 a 30\\\/5 - TV News\",\"headline\":\"O que rola em A Nobreza do Amor na semana 25 a 30\\\/5\",\"author\":{\"@id\":\"https:\\\/\\\/www.tvnovelas.com.br\\\/tvnews\\\/author\\\/pauloantonio\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.tvnovelas.com.br\\\/tvnews\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.tvnovelas.com.br\\\/tvnews\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/13288.jpg?fit=728%2C414&ssl=1\",\"width\":728,\"height\":414,\"caption\":\"O que rola em A Nobreza do Amor na semana 25 a 30\\\/5\"},\"datePublished\":\"2026-05-23T09:50:49-03:00\",\"dateModified\":\"2026-05-23T10:01:23-03:00\",\"inLanguage\":\"pt-BR\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tvnovelas.com.br\\\/tvnews\\\/o-que-rola-em-a-nobreza-do-amor-na-semana-25-a-30-5\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tvnovelas.com.br\\\/tvnews\\\/o-que-rola-em-a-nobreza-do-amor-na-semana-25-a-30-5\\\/#webpage\"},\"articleSection\":\"A Nobreza do Amor, A Nobreza do Amor, Globo, Novelas\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tvnovelas.com.br\\\/tvnews\\\/o-que-rola-em-a-nobreza-do-amor-na-semana-25-a-30-5\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.tvnovelas.com.br\\\/tvnews#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tvnovelas.com.br\\\/tvnews\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.tvnovelas.com.br\\\/tvnews\\\/category\\\/a-nobreza-do-amor\\\/#listItem\",\"name\":\"A Nobreza do Amor\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.tvnovelas.com.br\\\/tvnews\\\/category\\\/a-nobreza-do-amor\\\/#listItem\",\"position\":2,\"name\":\"A Nobreza do Amor\",\"item\":\"https:\\\/\\\/www.tvnovelas.com.br\\\/tvnews\\\/category\\\/a-nobreza-do-amor\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.tvnovelas.com.br\\\/tvnews\\\/o-que-rola-em-a-nobreza-do-amor-na-semana-25-a-30-5\\\/#listItem\",\"name\":\"O que rola em A Nobreza do Amor na semana 25 a 30\\\/5\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.tvnovelas.com.br\\\/tvnews#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.tvnovelas.com.br\\\/tvnews\\\/o-que-rola-em-a-nobreza-do-amor-na-semana-25-a-30-5\\\/#listItem\",\"position\":3,\"name\":\"O que rola em A Nobreza do Amor na semana 25 a 30\\\/5\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.tvnovelas.com.br\\\/tvnews\\\/category\\\/a-nobreza-do-amor\\\/#listItem\",\"name\":\"A Nobreza do Amor\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.tvnovelas.com.br\\\/tvnews\\\/#organization\",\"name\":\"TV Novelas\",\"description\":\"Se link nas novelas\",\"url\":\"https:\\\/\\\/www.tvnovelas.com.br\\\/tvnews\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.tvnovelas.com.br\\\/novelas\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/tvnovelas_logo.jpg\",\"@id\":\"https:\\\/\\\/www.tvnovelas.com.br\\\/tvnews\\\/o-que-rola-em-a-nobreza-do-amor-na-semana-25-a-30-5\\\/#organizationLogo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tvnovelas.com.br\\\/tvnews\\\/o-que-rola-em-a-nobreza-do-amor-na-semana-25-a-30-5\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/tevenovelas\\\/\",\"https:\\\/\\\/twitter.com\\\/TVNovelas\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tvnovelas.com.br\\\/tvnews\\\/author\\\/pauloantonio\\\/#author\",\"url\":\"https:\\\/\\\/www.tvnovelas.com.br\\\/tvnews\\\/author\\\/pauloantonio\\\/\",\"name\":\"Paulo Antonio\",\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/pauloantonyo\",\"https:\\\/\\\/facebook.com\\\/tevenovelas\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tvnovelas.com.br\\\/tvnews\\\/o-que-rola-em-a-nobreza-do-amor-na-semana-25-a-30-5\\\/#webpage\",\"url\":\"https:\\\/\\\/www.tvnovelas.com.br\\\/tvnews\\\/o-que-rola-em-a-nobreza-do-amor-na-semana-25-a-30-5\\\/\",\"name\":\"O que rola em A Nobreza do Amor na semana 25 a 30\\\/5 - TV News\",\"description\":\"O que rola em A Nobreza do Amor na semana 25 a 30\\\/5... Jendal manda por fogo nas doa\\u00e7\\u00f5es recebidas da Dinamarca; Os rebeldes saqueiam...\",\"inLanguage\":\"pt-BR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tvnovelas.com.br\\\/tvnews\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tvnovelas.com.br\\\/tvnews\\\/o-que-rola-em-a-nobreza-do-amor-na-semana-25-a-30-5\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.tvnovelas.com.br\\\/tvnews\\\/author\\\/pauloantonio\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.tvnovelas.com.br\\\/tvnews\\\/author\\\/pauloantonio\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/www.tvnovelas.com.br\\\/tvnews\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/13288.jpg?fit=728%2C414&ssl=1\",\"@id\":\"https:\\\/\\\/www.tvnovelas.com.br\\\/tvnews\\\/o-que-rola-em-a-nobreza-do-amor-na-semana-25-a-30-5\\\/#mainImage\",\"width\":728,\"height\":414,\"caption\":\"O que rola em A Nobreza do Amor na semana 25 a 30\\\/5\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tvnovelas.com.br\\\/tvnews\\\/o-que-rola-em-a-nobreza-do-amor-na-semana-25-a-30-5\\\/#mainImage\"},\"datePublished\":\"2026-05-23T09:50:49-03:00\",\"dateModified\":\"2026-05-23T10:01:23-03:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tvnovelas.com.br\\\/tvnews\\\/#website\",\"url\":\"https:\\\/\\\/www.tvnovelas.com.br\\\/tvnews\\\/\",\"name\":\"TV News\",\"description\":\"Se link nas novelas\",\"inLanguage\":\"pt-BR\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tvnovelas.com.br\\\/tvnews\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"O que rola em A Nobreza do Amor na semana 25 a 30\/5 - TV News","description":"O que rola em A Nobreza do Amor na semana 25 a 30\/5... Jendal manda por fogo nas doa\u00e7\u00f5es recebidas da Dinamarca; Os rebeldes saqueiam...","canonical_url":"https:\/\/www.tvnovelas.com.br\/tvnews\/o-que-rola-em-a-nobreza-do-amor-na-semana-25-a-30-5\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"google-site-verification":"rkK9U9oF3S28qRc6gTV5lXAuAQX2mzrSuD6qnebspv8","msvalidate.01":"AD79AA3D776A998E190189FA8E4A5338","miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tvnovelas.com.br\/tvnews\/o-que-rola-em-a-nobreza-do-amor-na-semana-25-a-30-5\/#article","name":"O que rola em A Nobreza do Amor na semana 25 a 30\/5 - TV News","headline":"O que rola em A Nobreza do Amor na semana 25 a 30\/5","author":{"@id":"https:\/\/www.tvnovelas.com.br\/tvnews\/author\/pauloantonio\/#author"},"publisher":{"@id":"https:\/\/www.tvnovelas.com.br\/tvnews\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/www.tvnovelas.com.br\/tvnews\/wp-content\/uploads\/2026\/05\/13288.jpg?fit=728%2C414&ssl=1","width":728,"height":414,"caption":"O que rola em A Nobreza do Amor na semana 25 a 30\/5"},"datePublished":"2026-05-23T09:50:49-03:00","dateModified":"2026-05-23T10:01:23-03:00","inLanguage":"pt-BR","mainEntityOfPage":{"@id":"https:\/\/www.tvnovelas.com.br\/tvnews\/o-que-rola-em-a-nobreza-do-amor-na-semana-25-a-30-5\/#webpage"},"isPartOf":{"@id":"https:\/\/www.tvnovelas.com.br\/tvnews\/o-que-rola-em-a-nobreza-do-amor-na-semana-25-a-30-5\/#webpage"},"articleSection":"A Nobreza do Amor, A Nobreza do Amor, Globo, Novelas"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tvnovelas.com.br\/tvnews\/o-que-rola-em-a-nobreza-do-amor-na-semana-25-a-30-5\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.tvnovelas.com.br\/tvnews#listItem","position":1,"name":"Home","item":"https:\/\/www.tvnovelas.com.br\/tvnews","nextItem":{"@type":"ListItem","@id":"https:\/\/www.tvnovelas.com.br\/tvnews\/category\/a-nobreza-do-amor\/#listItem","name":"A Nobreza do Amor"}},{"@type":"ListItem","@id":"https:\/\/www.tvnovelas.com.br\/tvnews\/category\/a-nobreza-do-amor\/#listItem","position":2,"name":"A Nobreza do Amor","item":"https:\/\/www.tvnovelas.com.br\/tvnews\/category\/a-nobreza-do-amor\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.tvnovelas.com.br\/tvnews\/o-que-rola-em-a-nobreza-do-amor-na-semana-25-a-30-5\/#listItem","name":"O que rola em A Nobreza do Amor na semana 25 a 30\/5"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.tvnovelas.com.br\/tvnews#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.tvnovelas.com.br\/tvnews\/o-que-rola-em-a-nobreza-do-amor-na-semana-25-a-30-5\/#listItem","position":3,"name":"O que rola em A Nobreza do Amor na semana 25 a 30\/5","previousItem":{"@type":"ListItem","@id":"https:\/\/www.tvnovelas.com.br\/tvnews\/category\/a-nobreza-do-amor\/#listItem","name":"A Nobreza do Amor"}}]},{"@type":"Organization","@id":"https:\/\/www.tvnovelas.com.br\/tvnews\/#organization","name":"TV Novelas","description":"Se link nas novelas","url":"https:\/\/www.tvnovelas.com.br\/tvnews\/","logo":{"@type":"ImageObject","url":"https:\/\/www.tvnovelas.com.br\/novelas\/wp-content\/uploads\/2018\/01\/tvnovelas_logo.jpg","@id":"https:\/\/www.tvnovelas.com.br\/tvnews\/o-que-rola-em-a-nobreza-do-amor-na-semana-25-a-30-5\/#organizationLogo"},"image":{"@id":"https:\/\/www.tvnovelas.com.br\/tvnews\/o-que-rola-em-a-nobreza-do-amor-na-semana-25-a-30-5\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/tevenovelas\/","https:\/\/twitter.com\/TVNovelas"]},{"@type":"Person","@id":"https:\/\/www.tvnovelas.com.br\/tvnews\/author\/pauloantonio\/#author","url":"https:\/\/www.tvnovelas.com.br\/tvnews\/author\/pauloantonio\/","name":"Paulo Antonio","sameAs":["https:\/\/facebook.com\/pauloantonyo","https:\/\/facebook.com\/tevenovelas"]},{"@type":"WebPage","@id":"https:\/\/www.tvnovelas.com.br\/tvnews\/o-que-rola-em-a-nobreza-do-amor-na-semana-25-a-30-5\/#webpage","url":"https:\/\/www.tvnovelas.com.br\/tvnews\/o-que-rola-em-a-nobreza-do-amor-na-semana-25-a-30-5\/","name":"O que rola em A Nobreza do Amor na semana 25 a 30\/5 - TV News","description":"O que rola em A Nobreza do Amor na semana 25 a 30\/5... Jendal manda por fogo nas doa\u00e7\u00f5es recebidas da Dinamarca; Os rebeldes saqueiam...","inLanguage":"pt-BR","isPartOf":{"@id":"https:\/\/www.tvnovelas.com.br\/tvnews\/#website"},"breadcrumb":{"@id":"https:\/\/www.tvnovelas.com.br\/tvnews\/o-que-rola-em-a-nobreza-do-amor-na-semana-25-a-30-5\/#breadcrumblist"},"author":{"@id":"https:\/\/www.tvnovelas.com.br\/tvnews\/author\/pauloantonio\/#author"},"creator":{"@id":"https:\/\/www.tvnovelas.com.br\/tvnews\/author\/pauloantonio\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/i0.wp.com\/www.tvnovelas.com.br\/tvnews\/wp-content\/uploads\/2026\/05\/13288.jpg?fit=728%2C414&ssl=1","@id":"https:\/\/www.tvnovelas.com.br\/tvnews\/o-que-rola-em-a-nobreza-do-amor-na-semana-25-a-30-5\/#mainImage","width":728,"height":414,"caption":"O que rola em A Nobreza do Amor na semana 25 a 30\/5"},"primaryImageOfPage":{"@id":"https:\/\/www.tvnovelas.com.br\/tvnews\/o-que-rola-em-a-nobreza-do-amor-na-semana-25-a-30-5\/#mainImage"},"datePublished":"2026-05-23T09:50:49-03:00","dateModified":"2026-05-23T10:01:23-03:00"},{"@type":"WebSite","@id":"https:\/\/www.tvnovelas.com.br\/tvnews\/#website","url":"https:\/\/www.tvnovelas.com.br\/tvnews\/","name":"TV News","description":"Se link nas novelas","inLanguage":"pt-BR","publisher":{"@id":"https:\/\/www.tvnovelas.com.br\/tvnews\/#organization"}}]},"og:locale":"pt_BR","og:site_name":"TV News","og:type":"article","og:title":"O que rola em A Nobreza do Amor na semana 25 a 30\/5 - TV News","og:description":"O que rola em A Nobreza do Amor na semana 25 a 30\/5... Jendal manda por fogo nas doa\u00e7\u00f5es recebidas da Dinamarca; Os rebeldes saqueiam...","og:url":"https:\/\/www.tvnovelas.com.br\/tvnews\/o-que-rola-em-a-nobreza-do-amor-na-semana-25-a-30-5\/","og:image":"https:\/\/www.tvnovelas.com.br\/tvshow\/wp-content\/uploads\/2018\/07\/tvnovelas_logo.jpg","og:image:secure_url":"https:\/\/www.tvnovelas.com.br\/tvshow\/wp-content\/uploads\/2018\/07\/tvnovelas_logo.jpg","article:tag":["a nobreza do amor","globo","novelas"],"article:published_time":"2026-05-23T12:50:49+00:00","article:modified_time":"2026-05-23T13:01:23+00:00","article:publisher":"https:\/\/www.facebook.com\/tevenovelas\/","article:author":"https:\/\/facebook.com\/pauloantonyo","twitter:card":"summary_large_image","twitter:site":"@TVNovelas","twitter:title":"O que rola em A Nobreza do Amor na semana 25 a 30\/5 - TV News","twitter:description":"O que rola em A Nobreza do Amor na semana 25 a 30\/5... Jendal manda por fogo nas doa\u00e7\u00f5es recebidas da Dinamarca; Os rebeldes saqueiam...","twitter:creator":"@TVNovelas","twitter:image":"https:\/\/www.tvnovelas.com.br\/tvshow\/wp-content\/uploads\/2018\/07\/tvnovelas_logo.jpg","twitter:label1":"Escrito por","twitter:data1":"Paulo Antonio","twitter:label2":"Tempo de leitura estimado","twitter:data2":"4 minutos"},"aioseo_meta_data":{"post_id":"90658","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"A Nobreza do Amor","score":91,"analysis":{"keyphraseInTitle":{"score":9,"maxScore":9,"error":0},"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":9,"maxScore":9,"error":0,"length":4},"keyphraseInURL":{"score":5,"maxScore":5,"error":0},"keyphraseInIntroduction":{"score":9,"maxScore":9,"error":0},"keyphraseInSubHeadings":{"score":3,"maxScore":9,"error":1},"keyphraseInImageAlt":{"score":9,"maxScore":9,"error":0},"keywordDensity":{"type":"best","score":9,"maxScore":9,"error":0}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"Article","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"schemas":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2026-05-22 14:44:59","updated":"2026-05-23 13:21:27","seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.tvnovelas.com.br\/tvnews\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/www.tvnovelas.com.br\/tvnews\/category\/a-nobreza-do-amor\/\" title=\"A Nobreza do Amor\">A Nobreza do Amor<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tO que rola em A Nobreza do Amor na semana 25 a 30\/5\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/www.tvnovelas.com.br\/tvnews"},{"label":"A Nobreza do Amor","link":"https:\/\/www.tvnovelas.com.br\/tvnews\/category\/a-nobreza-do-amor\/"},{"label":"O que rola em A Nobreza do Amor na semana 25 a 30\/5","link":"https:\/\/www.tvnovelas.com.br\/tvnews\/o-que-rola-em-a-nobreza-do-amor-na-semana-25-a-30-5\/"}],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.tvnovelas.com.br\/tvnews\/wp-content\/uploads\/2026\/05\/13288.jpg?fit=728%2C414&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/pdP2BO-nAe","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.tvnovelas.com.br\/tvnews\/wp-json\/wp\/v2\/posts\/90658","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tvnovelas.com.br\/tvnews\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tvnovelas.com.br\/tvnews\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tvnovelas.com.br\/tvnews\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tvnovelas.com.br\/tvnews\/wp-json\/wp\/v2\/comments?post=90658"}],"version-history":[{"count":4,"href":"https:\/\/www.tvnovelas.com.br\/tvnews\/wp-json\/wp\/v2\/posts\/90658\/revisions"}],"predecessor-version":[{"id":90689,"href":"https:\/\/www.tvnovelas.com.br\/tvnews\/wp-json\/wp\/v2\/posts\/90658\/revisions\/90689"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tvnovelas.com.br\/tvnews\/wp-json\/wp\/v2\/media\/90659"}],"wp:attachment":[{"href":"https:\/\/www.tvnovelas.com.br\/tvnews\/wp-json\/wp\/v2\/media?parent=90658"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tvnovelas.com.br\/tvnews\/wp-json\/wp\/v2\/categories?post=90658"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tvnovelas.com.br\/tvnews\/wp-json\/wp\/v2\/tags?post=90658"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}